{"id":46293,"date":"2026-04-02T00:02:55","date_gmt":"2026-04-01T21:02:55","guid":{"rendered":"https:\/\/rezekne.citro.lv\/veikals\/sokolades-batonins-mars-51g\/"},"modified":"2026-07-14T09:13:19","modified_gmt":"2026-07-14T06:13:19","slug":"sokolades-batonins-mars-51g","status":"publish","type":"product","link":"https:\/\/rezekne.citro.lv\/ru\/product\/sokolades-batonins-mars-51g\/","title":{"rendered":"\u0160OKOL\u0100DES BATONI\u0145\u0160 MARS 51G"},"content":{"rendered":"<p>Izcelsmes valsts: Valsts \u2013 nav zi\u0146u<\/p>\n","protected":false},"excerpt":{"rendered":"<p>15.49 \u20ac\/KG<\/p>\n","protected":false},"featured_media":46294,"template":"","meta":{"_acf_changed":false,"inline_featured_image":false},"product_cat":[125,134],"product_tag":[],"acf":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/rezekne.citro.lv\/ru\/wp-json\/wp\/v2\/product\/46293"}],"collection":[{"href":"https:\/\/rezekne.citro.lv\/ru\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/rezekne.citro.lv\/ru\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/rezekne.citro.lv\/ru\/wp-json\/wp\/v2\/media\/46294"}],"wp:attachment":[{"href":"https:\/\/rezekne.citro.lv\/ru\/wp-json\/wp\/v2\/media?parent=46293"}],"wp:term":[{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/rezekne.citro.lv\/ru\/wp-json\/wp\/v2\/product_cat?post=46293"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/rezekne.citro.lv\/ru\/wp-json\/wp\/v2\/product_tag?post=46293"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}